{"id":41,"count":1,"description":"","link":"https:\/\/kevbusiness.com\/blog\/category\/business\/","name":"BUSINESS","slug":"business","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BUSINESS archivos - Kevbusiness Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kevbusiness.com\/blog\/category\/business\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BUSINESS archivos - Kevbusiness Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kevbusiness.com\/blog\/category\/business\/\" \/>\n<meta property=\"og:site_name\" content=\"Kevbusiness Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/category\\\/business\\\/\",\"url\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/category\\\/business\\\/\",\"name\":\"BUSINESS archivos - Kevbusiness Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/category\\\/business\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/category\\\/business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BUSINESS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/\",\"name\":\"Kevbusiness Blog\",\"description\":\"Profesionales de la piedra\",\"publisher\":{\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/#organization\",\"name\":\"Kevbusiness Blog\",\"url\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-cropped-logo_340x_156-Fondo-blanco-1.jpg\",\"contentUrl\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-cropped-logo_340x_156-Fondo-blanco-1.jpg\",\"width\":339,\"height\":154,\"caption\":\"Kevbusiness Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/kevbusiness.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StoneKevbusiness\",\"https:\\\/\\\/www.instagram.com\\\/kev_cuarzo\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BUSINESS archivos - Kevbusiness Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kevbusiness.com\/blog\/category\/business\/","og_locale":"es_ES","og_type":"article","og_title":"BUSINESS archivos - Kevbusiness Blog","og_url":"https:\/\/kevbusiness.com\/blog\/category\/business\/","og_site_name":"Kevbusiness Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kevbusiness.com\/blog\/category\/business\/","url":"https:\/\/kevbusiness.com\/blog\/category\/business\/","name":"BUSINESS archivos - Kevbusiness Blog","isPartOf":{"@id":"https:\/\/kevbusiness.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/kevbusiness.com\/blog\/category\/business\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/kevbusiness.com\/blog\/category\/business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/kevbusiness.com\/blog\/"},{"@type":"ListItem","position":2,"name":"BUSINESS"}]},{"@type":"WebSite","@id":"https:\/\/kevbusiness.com\/blog\/#website","url":"https:\/\/kevbusiness.com\/blog\/","name":"Kevbusiness Blog","description":"Profesionales de la piedra","publisher":{"@id":"https:\/\/kevbusiness.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kevbusiness.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kevbusiness.com\/blog\/#organization","name":"Kevbusiness Blog","url":"https:\/\/kevbusiness.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kevbusiness.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/kevbusiness.com\/blog\/wp-content\/uploads\/2024\/12\/cropped-cropped-logo_340x_156-Fondo-blanco-1.jpg","contentUrl":"https:\/\/kevbusiness.com\/blog\/wp-content\/uploads\/2024\/12\/cropped-cropped-logo_340x_156-Fondo-blanco-1.jpg","width":339,"height":154,"caption":"Kevbusiness Blog"},"image":{"@id":"https:\/\/kevbusiness.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StoneKevbusiness","https:\/\/www.instagram.com\/kev_cuarzo\/"]}]}},"_links":{"self":[{"href":"https:\/\/kevbusiness.com\/blog\/wp-json\/wp\/v2\/categories\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kevbusiness.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kevbusiness.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kevbusiness.com\/blog\/wp-json\/wp\/v2\/posts?categories=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}